{"id":9851,"date":"2024-11-08T16:42:52","date_gmt":"2024-11-08T15:42:52","guid":{"rendered":"http:\/\/aurora.youelba.com\/appartamenti\/venus\/"},"modified":"2024-12-11T14:13:42","modified_gmt":"2024-12-11T13:13:42","slug":"venus","status":"publish","type":"page","link":"https:\/\/www.hotelauroraelba.it\/en\/apartments\/venus\/","title":{"rendered":"Venus apartment"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"9851\" class=\"elementor elementor-9851 elementor-8421\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ca6d065 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"ca6d065\" data-element_type=\"section\" data-settings=\"{&quot;shape_divider_bottom&quot;:&quot;wave-brush&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 283.5 27.8\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M283.5,9.7c0,0-7.3,4.3-14,4.6c-6.8,0.3-12.6,0-20.9-1.5c-11.3-2-33.1-10.1-44.7-5.7\ts-12.1,4.6-18,7.4c-6.6,3.2-20,9.6-36.6,9.3C131.6,23.5,99.5,7.2,86.3,8c-1.4,0.1-6.6,0.8-10.5,2c-3.8,1.2-9.4,3.8-17,4.7\tc-3.2,0.4-8.3,1.1-14.2,0.9c-1.5-0.1-6.3-0.4-12-1.6c-5.7-1.2-11-3.1-15.8-3.7C6.5,9.2,0,10.8,0,10.8V0h283.5V9.7z M260.8,11.3\tc-0.7-1-2-0.4-4.3-0.4c-2.3,0-6.1-1.2-5.8-1.1c0.3,0.1,3.1,1.5,6,1.9C259.7,12.2,261.4,12.3,260.8,11.3z M242.4,8.6\tc0,0-2.4-0.2-5.6-0.9c-3.2-0.8-10.3-2.8-15.1-3.5c-8.2-1.1-15.8,0-15.1,0.1c0.8,0.1,9.6-0.6,17.6,1.1c3.3,0.7,9.3,2.2,12.4,2.7\tC239.9,8.7,242.4,8.6,242.4,8.6z M185.2,8.5c1.7-0.7-13.3,4.7-18.5,6.1c-2.1,0.6-6.2,1.6-10,2c-3.9,0.4-8.9,0.4-8.8,0.5\tc0,0.2,5.8,0.8,11.2,0c5.4-0.8,5.2-1.1,7.6-1.6C170.5,14.7,183.5,9.2,185.2,8.5z M199.1,6.9c0.2,0-0.8-0.4-4.8,1.1\tc-4,1.5-6.7,3.5-6.9,3.7c-0.2,0.1,3.5-1.8,6.6-3C197,7.5,199,6.9,199.1,6.9z M283,6c-0.1,0.1-1.9,1.1-4.8,2.5s-6.9,2.8-6.7,2.7\tc0.2,0,3.5-0.6,7.4-2.5C282.8,6.8,283.1,5.9,283,6z M31.3,11.6c0.1-0.2-1.9-0.2-4.5-1.2s-5.4-1.6-7.8-2C15,7.6,7.3,8.5,7.7,8.6\tC8,8.7,15.9,8.3,20.2,9.3c2.2,0.5,2.4,0.5,5.7,1.6S31.2,11.9,31.3,11.6z M73,9.2c0.4-0.1,3.5-1.6,8.4-2.6c4.9-1.1,8.9-0.5,8.9-0.8\tc0-0.3-1-0.9-6.2-0.3S72.6,9.3,73,9.2z M71.6,6.7C71.8,6.8,75,5.4,77.3,5c2.3-0.3,1.9-0.5,1.9-0.6c0-0.1-1.1-0.2-2.7,0.2\tC74.8,5.1,71.4,6.6,71.6,6.7z M93.6,4.4c0.1,0.2,3.5,0.8,5.6,1.8c2.1,1,1.8,0.6,1.9,0.5c0.1-0.1-0.8-0.8-2.4-1.3\tC97.1,4.8,93.5,4.2,93.6,4.4z M65.4,11.1c-0.1,0.3,0.3,0.5,1.9-0.2s2.6-1.3,2.2-1.2s-0.9,0.4-2.5,0.8C65.3,10.9,65.5,10.8,65.4,11.1\tz M34.5,12.4c-0.2,0,2.1,0.8,3.3,0.9c1.2,0.1,2,0.1,2-0.2c0-0.3-0.1-0.5-1.6-0.4C36.6,12.8,34.7,12.4,34.5,12.4z M152.2,21.1\tc-0.1,0.1-2.4-0.3-7.5-0.3c-5,0-13.6-2.4-17.2-3.5c-3.6-1.1,10,3.9,16.5,4.1C150.5,21.6,152.3,21,152.2,21.1z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M269.6,18c-0.1-0.1-4.6,0.3-7.2,0c-7.3-0.7-17-3.2-16.6-2.9c0.4,0.3,13.7,3.1,17,3.3\tC267.7,18.8,269.7,18,269.6,18z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M227.4,9.8c-0.2-0.1-4.5-1-9.5-1.2c-5-0.2-12.7,0.6-12.3,0.5c0.3-0.1,5.9-1.8,13.3-1.2\tS227.6,9.9,227.4,9.8z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M204.5,13.4c-0.1-0.1,2-1,3.2-1.1c1.2-0.1,2,0,2,0.3c0,0.3-0.1,0.5-1.6,0.4\tC206.4,12.9,204.6,13.5,204.5,13.4z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M201,10.6c0-0.1-4.4,1.2-6.3,2.2c-1.9,0.9-6.2,3.1-6.1,3.1c0.1,0.1,4.2-1.6,6.3-2.6\tS201,10.7,201,10.6z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M154.5,26.7c-0.1-0.1-4.6,0.3-7.2,0c-7.3-0.7-17-3.2-16.6-2.9c0.4,0.3,13.7,3.1,17,3.3\tC152.6,27.5,154.6,26.8,154.5,26.7z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M41.9,19.3c0,0,1.2-0.3,2.9-0.1c1.7,0.2,5.8,0.9,8.2,0.7c4.2-0.4,7.4-2.7,7-2.6\tc-0.4,0-4.3,2.2-8.6,1.9c-1.8-0.1-5.1-0.5-6.7-0.4S41.9,19.3,41.9,19.3z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M75.5,12.6c0.2,0.1,2-0.8,4.3-1.1c2.3-0.2,2.1-0.3,2.1-0.5c0-0.1-1.8-0.4-3.4,0\tC76.9,11.5,75.3,12.5,75.5,12.6z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M15.6,13.2c0-0.1,4.3,0,6.7,0.5c2.4,0.5,5,1.9,5,2c0,0.1-2.7-0.8-5.1-1.4\tC19.9,13.7,15.7,13.3,15.6,13.2z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-eee7acd\" data-id=\"eee7acd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1db2167 elementor-widget elementor-widget-kinsley-intro\" data-id=\"1db2167\" data-element_type=\"widget\" data-widget_type=\"kinsley-intro.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n    <!-- banner -->\n    <section class=\"knsl-banner-simple knsl-transition-bottom knsl-banner-white\">\n      \n\t  \t  <div class=\"knsl-cover-frame\">\n\t\t\t\t\t\t<div style=\"background-image: url('https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/htl-aurora-app-venus-4247-8t.jpg');\" class=\"knsl-parallax knsl-banner-slide\"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t  <div class=\"knsl-overlay\" style=\"opacity: 0.2;\"><\/div>\n\t  \n      <div class=\"container\">\n        <div class=\"row\">\n          <div class=\"col-lg-12\">\n\n            <div class=\"knsl-center knsl-title-frame title-pos-top\">\n                            <h1 class=\"knsl-title--h knsl-mb-20 knsl-h1-inner\">\n                <span >\n                    Venus Apartment                <\/span>\n              <\/h1>\n                            \n              <ul class=\"knsl-breadcrumbs\"><li><a href=\"https:\/\/www.hotelauroraelba.it\/en\/\" title=\"Hotel Aurora Elba\">Home<\/a><\/li><li><a href=\"https:\/\/www.hotelauroraelba.it\/en\/apartments\/\">Apartments<\/a><\/li><li class=\"tst-active\"><a><\/a><\/li><\/ul>\n            <\/div>\n\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/section>\n    <!-- banner end -->\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6a188f7 elementor-section-content-middle elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6a188f7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-87724dd\" data-id=\"87724dd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7a5b920 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7a5b920\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8d92ed1\" data-id=\"8d92ed1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-780a644 elementor-widget elementor-widget-heading\" data-id=\"780a644\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">for 6 people<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a9c9db elementor-widget elementor-widget-heading\" data-id=\"2a9c9db\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Outdoor patio with a sea view<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ea9d72c elementor-widget elementor-widget-text-editor\" data-id=\"ea9d72c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Located on the ground floor, this apartment features a living area with a sea view, a kitchen and dining area with a double sofa bed, an external patio with a sea view for dining, a double bedroom, a twin bedroom, and a bathroom with a shower.<\/p><p>Equipped with all amenities, it can accommodate up to 6 people!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d817c7c elementor-widget elementor-widget-kinsley-buttons\" data-id=\"d817c7c\" data-element_type=\"widget\" data-widget_type=\"kinsley-buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <!-- action button -->\n        <a  target=\"_blank\" href=\"https:\/\/smartbooking.fastreplymail.it\/home\/main?hotel=9875&amp;channel=0000&amp;lingua=GB\" class=\"knsl-btn knsl-btn-md\">\n                        <span >\n            Book now            <\/span>\n        <\/a>\n        <!-- action button end -->\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7e77b9b\" data-id=\"7e77b9b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-87cc45a elementor-widget elementor-widget-image\" data-id=\"87cc45a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"900\" height=\"675\" src=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/htl-aurora-app-venus-4290-27-1024x768.jpg\" class=\"attachment-large size-large wp-image-8440\" alt=\"Soggiorno Appartamento Venus\" srcset=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/htl-aurora-app-venus-4290-27-1024x768.jpg 1024w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/htl-aurora-app-venus-4290-27-300x225.jpg 300w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/htl-aurora-app-venus-4290-27-768x576.jpg 768w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/htl-aurora-app-venus-4290-27-1536x1152.jpg 1536w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/htl-aurora-app-venus-4290-27-950x713.jpg 950w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/htl-aurora-app-venus-4290-27-800x600.jpg 800w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/htl-aurora-app-venus-4290-27.jpg 1920w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-65dd282 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"65dd282\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_top&quot;:&quot;wave-brush&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 283.5 27.8\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M283.5,9.7c0,0-7.3,4.3-14,4.6c-6.8,0.3-12.6,0-20.9-1.5c-11.3-2-33.1-10.1-44.7-5.7\ts-12.1,4.6-18,7.4c-6.6,3.2-20,9.6-36.6,9.3C131.6,23.5,99.5,7.2,86.3,8c-1.4,0.1-6.6,0.8-10.5,2c-3.8,1.2-9.4,3.8-17,4.7\tc-3.2,0.4-8.3,1.1-14.2,0.9c-1.5-0.1-6.3-0.4-12-1.6c-5.7-1.2-11-3.1-15.8-3.7C6.5,9.2,0,10.8,0,10.8V0h283.5V9.7z M260.8,11.3\tc-0.7-1-2-0.4-4.3-0.4c-2.3,0-6.1-1.2-5.8-1.1c0.3,0.1,3.1,1.5,6,1.9C259.7,12.2,261.4,12.3,260.8,11.3z M242.4,8.6\tc0,0-2.4-0.2-5.6-0.9c-3.2-0.8-10.3-2.8-15.1-3.5c-8.2-1.1-15.8,0-15.1,0.1c0.8,0.1,9.6-0.6,17.6,1.1c3.3,0.7,9.3,2.2,12.4,2.7\tC239.9,8.7,242.4,8.6,242.4,8.6z M185.2,8.5c1.7-0.7-13.3,4.7-18.5,6.1c-2.1,0.6-6.2,1.6-10,2c-3.9,0.4-8.9,0.4-8.8,0.5\tc0,0.2,5.8,0.8,11.2,0c5.4-0.8,5.2-1.1,7.6-1.6C170.5,14.7,183.5,9.2,185.2,8.5z M199.1,6.9c0.2,0-0.8-0.4-4.8,1.1\tc-4,1.5-6.7,3.5-6.9,3.7c-0.2,0.1,3.5-1.8,6.6-3C197,7.5,199,6.9,199.1,6.9z M283,6c-0.1,0.1-1.9,1.1-4.8,2.5s-6.9,2.8-6.7,2.7\tc0.2,0,3.5-0.6,7.4-2.5C282.8,6.8,283.1,5.9,283,6z M31.3,11.6c0.1-0.2-1.9-0.2-4.5-1.2s-5.4-1.6-7.8-2C15,7.6,7.3,8.5,7.7,8.6\tC8,8.7,15.9,8.3,20.2,9.3c2.2,0.5,2.4,0.5,5.7,1.6S31.2,11.9,31.3,11.6z M73,9.2c0.4-0.1,3.5-1.6,8.4-2.6c4.9-1.1,8.9-0.5,8.9-0.8\tc0-0.3-1-0.9-6.2-0.3S72.6,9.3,73,9.2z M71.6,6.7C71.8,6.8,75,5.4,77.3,5c2.3-0.3,1.9-0.5,1.9-0.6c0-0.1-1.1-0.2-2.7,0.2\tC74.8,5.1,71.4,6.6,71.6,6.7z M93.6,4.4c0.1,0.2,3.5,0.8,5.6,1.8c2.1,1,1.8,0.6,1.9,0.5c0.1-0.1-0.8-0.8-2.4-1.3\tC97.1,4.8,93.5,4.2,93.6,4.4z M65.4,11.1c-0.1,0.3,0.3,0.5,1.9-0.2s2.6-1.3,2.2-1.2s-0.9,0.4-2.5,0.8C65.3,10.9,65.5,10.8,65.4,11.1\tz M34.5,12.4c-0.2,0,2.1,0.8,3.3,0.9c1.2,0.1,2,0.1,2-0.2c0-0.3-0.1-0.5-1.6-0.4C36.6,12.8,34.7,12.4,34.5,12.4z M152.2,21.1\tc-0.1,0.1-2.4-0.3-7.5-0.3c-5,0-13.6-2.4-17.2-3.5c-3.6-1.1,10,3.9,16.5,4.1C150.5,21.6,152.3,21,152.2,21.1z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M269.6,18c-0.1-0.1-4.6,0.3-7.2,0c-7.3-0.7-17-3.2-16.6-2.9c0.4,0.3,13.7,3.1,17,3.3\tC267.7,18.8,269.7,18,269.6,18z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M227.4,9.8c-0.2-0.1-4.5-1-9.5-1.2c-5-0.2-12.7,0.6-12.3,0.5c0.3-0.1,5.9-1.8,13.3-1.2\tS227.6,9.9,227.4,9.8z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M204.5,13.4c-0.1-0.1,2-1,3.2-1.1c1.2-0.1,2,0,2,0.3c0,0.3-0.1,0.5-1.6,0.4\tC206.4,12.9,204.6,13.5,204.5,13.4z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M201,10.6c0-0.1-4.4,1.2-6.3,2.2c-1.9,0.9-6.2,3.1-6.1,3.1c0.1,0.1,4.2-1.6,6.3-2.6\tS201,10.7,201,10.6z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M154.5,26.7c-0.1-0.1-4.6,0.3-7.2,0c-7.3-0.7-17-3.2-16.6-2.9c0.4,0.3,13.7,3.1,17,3.3\tC152.6,27.5,154.6,26.8,154.5,26.7z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M41.9,19.3c0,0,1.2-0.3,2.9-0.1c1.7,0.2,5.8,0.9,8.2,0.7c4.2-0.4,7.4-2.7,7-2.6\tc-0.4,0-4.3,2.2-8.6,1.9c-1.8-0.1-5.1-0.5-6.7-0.4S41.9,19.3,41.9,19.3z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M75.5,12.6c0.2,0.1,2-0.8,4.3-1.1c2.3-0.2,2.1-0.3,2.1-0.5c0-0.1-1.8-0.4-3.4,0\tC76.9,11.5,75.3,12.5,75.5,12.6z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M15.6,13.2c0-0.1,4.3,0,6.7,0.5c2.4,0.5,5,1.9,5,2c0,0.1-2.7-0.8-5.1-1.4\tC19.9,13.7,15.7,13.3,15.6,13.2z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-646e7b9\" data-id=\"646e7b9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-77ad4ce elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"77ad4ce\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-186ba01\" data-id=\"186ba01\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a74de99 elementor-widget elementor-widget-heading\" data-id=\"a74de99\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Apartment Services<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a5bdc83 elementor-widget elementor-widget-heading\" data-id=\"a5bdc83\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">All the comfort you need<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-d5198e7 e-flex e-con-boxed e-con e-parent\" data-id=\"d5198e7\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8276dc0 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"8276dc0\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/beach.png\" class=\"attachment-full size-full wp-image-8325\" alt=\"\" srcset=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/beach.png 512w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/beach-300x300.png 300w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/beach-150x150.png 150w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/beach-140x140.png 140w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/beach-256x256.png 256w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/beach-100x100.png 100w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Living area, terrace, balcony, or patio with sea view<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c533b1e elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"c533b1e\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"498\" height=\"498\" src=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2021\/12\/f-6.png\" class=\"attachment-full size-full wp-image-312\" alt=\"\" srcset=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2021\/12\/f-6.png 498w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2021\/12\/f-6-100x100.png 100w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2021\/12\/f-6-300x300.png 300w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2021\/12\/f-6-150x150.png 150w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2021\/12\/f-6-140x140.png 140w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2021\/12\/f-6-256x256.png 256w\" sizes=\"(max-width: 498px) 100vw, 498px\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Free Wi-Fi\n<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8eddcb3 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"8eddcb3\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"352\" src=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2023\/08\/f-3.png\" class=\"attachment-full size-full wp-image-4529\" alt=\"\" srcset=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2023\/08\/f-3.png 496w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2023\/08\/f-3-300x213.png 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Multifunction air conditioning<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fbe661d elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"fbe661d\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/tv-monitor.png\" class=\"attachment-full size-full wp-image-8164\" alt=\"\" srcset=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/tv-monitor.png 512w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/tv-monitor-300x300.png 300w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/tv-monitor-150x150.png 150w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/tv-monitor-140x140.png 140w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/tv-monitor-256x256.png 256w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/tv-monitor-100x100.png 100w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Flat-screen TV with Tiv\u00f9sat satellite channels<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c83a1ea elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"c83a1ea\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/safe.png\" class=\"attachment-full size-full wp-image-8163\" alt=\"\" srcset=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/safe.png 512w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/safe-300x300.png 300w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/safe-150x150.png 150w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/safe-140x140.png 140w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/safe-256x256.png 256w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/safe-100x100.png 100w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">safe<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f2eae0 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"7f2eae0\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/parking.png\" class=\"attachment-full size-full wp-image-8338\" alt=\"\" srcset=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/parking.png 512w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/parking-300x300.png 300w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/parking-150x150.png 150w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/parking-140x140.png 140w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/parking-256x256.png 256w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/parking-100x100.png 100w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Free reserved parking<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e6562e7 e-flex e-con-boxed e-con e-parent\" data-id=\"e6562e7\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-27d58f3 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"27d58f3\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/kitchen-set.png\" class=\"attachment-full size-full wp-image-8324\" alt=\"\" srcset=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/kitchen-set.png 512w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/kitchen-set-300x300.png 300w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/kitchen-set-150x150.png 150w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/kitchen-set-140x140.png 140w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/kitchen-set-256x256.png 256w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/kitchen-set-100x100.png 100w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Private kitchen with induction cooktops<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a1c4d86 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"a1c4d86\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/spatula.png\" class=\"attachment-full size-full wp-image-8327\" alt=\"\" srcset=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/spatula.png 512w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/spatula-300x300.png 300w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/spatula-150x150.png 150w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/spatula-140x140.png 140w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/spatula-256x256.png 256w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/spatula-100x100.png 100w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Cooking utensils and accessories<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3094281 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"3094281\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/fridge.png\" class=\"attachment-full size-full wp-image-8329\" alt=\"\" srcset=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/fridge.png 512w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/fridge-300x300.png 300w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/fridge-150x150.png 150w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/fridge-140x140.png 140w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/fridge-256x256.png 256w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/fridge-100x100.png 100w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Fridge<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f7ea658 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"f7ea658\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/dishwasher.png\" class=\"attachment-full size-full wp-image-8328\" alt=\"\" srcset=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/dishwasher.png 512w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/dishwasher-300x300.png 300w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/dishwasher-150x150.png 150w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/dishwasher-140x140.png 140w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/dishwasher-256x256.png 256w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/dishwasher-100x100.png 100w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Dishwasher<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba9c2c7 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"ba9c2c7\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/espresso.png\" class=\"attachment-full size-full wp-image-8332\" alt=\"\" srcset=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/espresso.png 512w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/espresso-300x300.png 300w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/espresso-150x150.png 150w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/espresso-140x140.png 140w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/espresso-256x256.png 256w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/espresso-100x100.png 100w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Hyperespresso coffee machine<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b447c5f elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"b447c5f\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/kettle.png\" class=\"attachment-full size-full wp-image-8331\" alt=\"\" srcset=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/kettle.png 512w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/kettle-300x300.png 300w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/kettle-150x150.png 150w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/kettle-140x140.png 140w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/kettle-256x256.png 256w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/kettle-100x100.png 100w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Kettle<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a363795 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"a363795\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/oven.png\" class=\"attachment-full size-full wp-image-8330\" alt=\"\" srcset=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/oven.png 512w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/oven-300x300.png 300w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/oven-150x150.png 150w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/oven-140x140.png 140w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/oven-256x256.png 256w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/oven-100x100.png 100w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Combined microwave oven<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b413426 e-flex e-con-boxed e-con e-parent\" data-id=\"b413426\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4481463 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"4481463\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/steam-iron.png\" class=\"attachment-full size-full wp-image-8337\" alt=\"\" srcset=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/steam-iron.png 512w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/steam-iron-300x300.png 300w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/steam-iron-150x150.png 150w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/steam-iron-140x140.png 140w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/steam-iron-256x256.png 256w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/steam-iron-100x100.png 100w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Iron and ironing board<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76b5d73 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"76b5d73\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/vacuum-cleaner.png\" class=\"attachment-full size-full wp-image-8336\" alt=\"\" srcset=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/vacuum-cleaner.png 512w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/vacuum-cleaner-300x300.png 300w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/vacuum-cleaner-150x150.png 150w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/vacuum-cleaner-140x140.png 140w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/vacuum-cleaner-256x256.png 256w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/vacuum-cleaner-100x100.png 100w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Vacuum cleaner<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c7b108 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"8c7b108\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/machine.png\" class=\"attachment-full size-full wp-image-8167\" alt=\"\" srcset=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/machine.png 512w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/machine-300x300.png 300w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/machine-150x150.png 150w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/machine-140x140.png 140w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/machine-256x256.png 256w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/machine-100x100.png 100w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Bathroom with shower and hairdryer available<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-78ae757 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"78ae757\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/cleaning.png\" class=\"attachment-full size-full wp-image-8335\" alt=\"\" srcset=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/cleaning.png 512w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/cleaning-300x300.png 300w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/cleaning-150x150.png 150w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/cleaning-140x140.png 140w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/cleaning-256x256.png 256w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/cleaning-100x100.png 100w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Cleaning products<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30848a7 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"30848a7\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/blanket.png\" class=\"attachment-full size-full wp-image-8334\" alt=\"\" srcset=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/blanket.png 512w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/blanket-300x300.png 300w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/blanket-150x150.png 150w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/blanket-140x140.png 140w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/blanket-256x256.png 256w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/blanket-100x100.png 100w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Linen included<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a9ba00 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"4a9ba00\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/laundry-machine.png\" class=\"attachment-full size-full wp-image-8333\" alt=\"\" srcset=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/laundry-machine.png 512w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/laundry-machine-300x300.png 300w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/laundry-machine-150x150.png 150w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/laundry-machine-140x140.png 140w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/laundry-machine-256x256.png 256w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/laundry-machine-100x100.png 100w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Washing machine<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8028548 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8028548\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_bottom&quot;:&quot;wave-brush&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 283.5 27.8\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M283.5,9.7c0,0-7.3,4.3-14,4.6c-6.8,0.3-12.6,0-20.9-1.5c-11.3-2-33.1-10.1-44.7-5.7\ts-12.1,4.6-18,7.4c-6.6,3.2-20,9.6-36.6,9.3C131.6,23.5,99.5,7.2,86.3,8c-1.4,0.1-6.6,0.8-10.5,2c-3.8,1.2-9.4,3.8-17,4.7\tc-3.2,0.4-8.3,1.1-14.2,0.9c-1.5-0.1-6.3-0.4-12-1.6c-5.7-1.2-11-3.1-15.8-3.7C6.5,9.2,0,10.8,0,10.8V0h283.5V9.7z M260.8,11.3\tc-0.7-1-2-0.4-4.3-0.4c-2.3,0-6.1-1.2-5.8-1.1c0.3,0.1,3.1,1.5,6,1.9C259.7,12.2,261.4,12.3,260.8,11.3z M242.4,8.6\tc0,0-2.4-0.2-5.6-0.9c-3.2-0.8-10.3-2.8-15.1-3.5c-8.2-1.1-15.8,0-15.1,0.1c0.8,0.1,9.6-0.6,17.6,1.1c3.3,0.7,9.3,2.2,12.4,2.7\tC239.9,8.7,242.4,8.6,242.4,8.6z M185.2,8.5c1.7-0.7-13.3,4.7-18.5,6.1c-2.1,0.6-6.2,1.6-10,2c-3.9,0.4-8.9,0.4-8.8,0.5\tc0,0.2,5.8,0.8,11.2,0c5.4-0.8,5.2-1.1,7.6-1.6C170.5,14.7,183.5,9.2,185.2,8.5z M199.1,6.9c0.2,0-0.8-0.4-4.8,1.1\tc-4,1.5-6.7,3.5-6.9,3.7c-0.2,0.1,3.5-1.8,6.6-3C197,7.5,199,6.9,199.1,6.9z M283,6c-0.1,0.1-1.9,1.1-4.8,2.5s-6.9,2.8-6.7,2.7\tc0.2,0,3.5-0.6,7.4-2.5C282.8,6.8,283.1,5.9,283,6z M31.3,11.6c0.1-0.2-1.9-0.2-4.5-1.2s-5.4-1.6-7.8-2C15,7.6,7.3,8.5,7.7,8.6\tC8,8.7,15.9,8.3,20.2,9.3c2.2,0.5,2.4,0.5,5.7,1.6S31.2,11.9,31.3,11.6z M73,9.2c0.4-0.1,3.5-1.6,8.4-2.6c4.9-1.1,8.9-0.5,8.9-0.8\tc0-0.3-1-0.9-6.2-0.3S72.6,9.3,73,9.2z M71.6,6.7C71.8,6.8,75,5.4,77.3,5c2.3-0.3,1.9-0.5,1.9-0.6c0-0.1-1.1-0.2-2.7,0.2\tC74.8,5.1,71.4,6.6,71.6,6.7z M93.6,4.4c0.1,0.2,3.5,0.8,5.6,1.8c2.1,1,1.8,0.6,1.9,0.5c0.1-0.1-0.8-0.8-2.4-1.3\tC97.1,4.8,93.5,4.2,93.6,4.4z M65.4,11.1c-0.1,0.3,0.3,0.5,1.9-0.2s2.6-1.3,2.2-1.2s-0.9,0.4-2.5,0.8C65.3,10.9,65.5,10.8,65.4,11.1\tz M34.5,12.4c-0.2,0,2.1,0.8,3.3,0.9c1.2,0.1,2,0.1,2-0.2c0-0.3-0.1-0.5-1.6-0.4C36.6,12.8,34.7,12.4,34.5,12.4z M152.2,21.1\tc-0.1,0.1-2.4-0.3-7.5-0.3c-5,0-13.6-2.4-17.2-3.5c-3.6-1.1,10,3.9,16.5,4.1C150.5,21.6,152.3,21,152.2,21.1z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M269.6,18c-0.1-0.1-4.6,0.3-7.2,0c-7.3-0.7-17-3.2-16.6-2.9c0.4,0.3,13.7,3.1,17,3.3\tC267.7,18.8,269.7,18,269.6,18z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M227.4,9.8c-0.2-0.1-4.5-1-9.5-1.2c-5-0.2-12.7,0.6-12.3,0.5c0.3-0.1,5.9-1.8,13.3-1.2\tS227.6,9.9,227.4,9.8z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M204.5,13.4c-0.1-0.1,2-1,3.2-1.1c1.2-0.1,2,0,2,0.3c0,0.3-0.1,0.5-1.6,0.4\tC206.4,12.9,204.6,13.5,204.5,13.4z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M201,10.6c0-0.1-4.4,1.2-6.3,2.2c-1.9,0.9-6.2,3.1-6.1,3.1c0.1,0.1,4.2-1.6,6.3-2.6\tS201,10.7,201,10.6z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M154.5,26.7c-0.1-0.1-4.6,0.3-7.2,0c-7.3-0.7-17-3.2-16.6-2.9c0.4,0.3,13.7,3.1,17,3.3\tC152.6,27.5,154.6,26.8,154.5,26.7z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M41.9,19.3c0,0,1.2-0.3,2.9-0.1c1.7,0.2,5.8,0.9,8.2,0.7c4.2-0.4,7.4-2.7,7-2.6\tc-0.4,0-4.3,2.2-8.6,1.9c-1.8-0.1-5.1-0.5-6.7-0.4S41.9,19.3,41.9,19.3z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M75.5,12.6c0.2,0.1,2-0.8,4.3-1.1c2.3-0.2,2.1-0.3,2.1-0.5c0-0.1-1.8-0.4-3.4,0\tC76.9,11.5,75.3,12.5,75.5,12.6z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M15.6,13.2c0-0.1,4.3,0,6.7,0.5c2.4,0.5,5,1.9,5,2c0,0.1-2.7-0.8-5.1-1.4\tC19.9,13.7,15.7,13.3,15.6,13.2z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-22dbaac\" data-id=\"22dbaac\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ee4c80 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"7ee4c80\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/no-pets-allowed.png\" class=\"attachment-full size-full wp-image-8323\" alt=\"\" srcset=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/no-pets-allowed.png 512w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/no-pets-allowed-300x300.png 300w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/no-pets-allowed-150x150.png 150w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/no-pets-allowed-140x140.png 140w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/no-pets-allowed-256x256.png 256w, https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/no-pets-allowed-100x100.png 100w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">No pets allowed<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d982821 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"d982821\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-89b1209\" data-id=\"89b1209\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1537f28 elementor-widget elementor-widget-kinsley-about-gallery\" data-id=\"1537f28\" data-element_type=\"widget\" data-widget_type=\"kinsley-about-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<!-- gallery -->\n\t  <section class=\"knsl-transition-none knsl-p-0-100\">\n    \t\n\t\t        <div class=\"row align-items-center\">\n          \n                    <div class=\"col-lg-12 knsl-about-slider-fully\">\n\n            <!-- slider -->\n            <div class=\"swiper-container knsl-about-slider knsl-scroll-animation\">\n              <div class=\"swiper-wrapper\">\n                                <div class=\"swiper-slide\">\n\n                  <!-- gallery item -->\n                  <div class=\"knsl-image-frame\">\n                  \t                    \t\t\t\t\t<a data-elementor-lightbox-slideshow=\"about-gallery\" data-elementor-lightbox-title=\"\" href=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/htl-aurora-app-venus-4239-2.jpg\">\n\t\t\t\t\t                      <img decoding=\"async\" src=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/htl-aurora-app-venus-4239-2.jpg\" alt=\"\" \/>\n                                            <span class=\"knsl-zoom\"><i class=\"fas fa-search-plus\"><\/i><\/span>\n                    <\/a>\n                                      <\/div>\n                  <!-- gallery item end -->\n\n                <\/div>\n                                <div class=\"swiper-slide\">\n\n                  <!-- gallery item -->\n                  <div class=\"knsl-image-frame\">\n                  \t                    \t\t\t\t\t<a data-elementor-lightbox-slideshow=\"about-gallery\" data-elementor-lightbox-title=\"\" href=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/htl-aurora-app-venus-4278-21.jpg\">\n\t\t\t\t\t                      <img decoding=\"async\" src=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/htl-aurora-app-venus-4278-21.jpg\" alt=\"\" \/>\n                                            <span class=\"knsl-zoom\"><i class=\"fas fa-search-plus\"><\/i><\/span>\n                    <\/a>\n                                      <\/div>\n                  <!-- gallery item end -->\n\n                <\/div>\n                                <div class=\"swiper-slide\">\n\n                  <!-- gallery item -->\n                  <div class=\"knsl-image-frame\">\n                  \t                    \t\t\t\t\t<a data-elementor-lightbox-slideshow=\"about-gallery\" data-elementor-lightbox-title=\"\" href=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/htl-aurora-app-venus-4280-22.jpg\">\n\t\t\t\t\t                      <img decoding=\"async\" src=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/htl-aurora-app-venus-4280-22.jpg\" alt=\"\" \/>\n                                            <span class=\"knsl-zoom\"><i class=\"fas fa-search-plus\"><\/i><\/span>\n                    <\/a>\n                                      <\/div>\n                  <!-- gallery item end -->\n\n                <\/div>\n                                <div class=\"swiper-slide\">\n\n                  <!-- gallery item -->\n                  <div class=\"knsl-image-frame\">\n                  \t                    \t\t\t\t\t<a data-elementor-lightbox-slideshow=\"about-gallery\" data-elementor-lightbox-title=\"\" href=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/htl-aurora-app-venus-4283-23.jpg\">\n\t\t\t\t\t                      <img decoding=\"async\" src=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/htl-aurora-app-venus-4283-23.jpg\" alt=\"\" \/>\n                                            <span class=\"knsl-zoom\"><i class=\"fas fa-search-plus\"><\/i><\/span>\n                    <\/a>\n                                      <\/div>\n                  <!-- gallery item end -->\n\n                <\/div>\n                                <div class=\"swiper-slide\">\n\n                  <!-- gallery item -->\n                  <div class=\"knsl-image-frame\">\n                  \t                    \t\t\t\t\t<a data-elementor-lightbox-slideshow=\"about-gallery\" data-elementor-lightbox-title=\"\" href=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/htl-aurora-app-venus-4284-24.jpg\">\n\t\t\t\t\t                      <img decoding=\"async\" src=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/htl-aurora-app-venus-4284-24.jpg\" alt=\"\" \/>\n                                            <span class=\"knsl-zoom\"><i class=\"fas fa-search-plus\"><\/i><\/span>\n                    <\/a>\n                                      <\/div>\n                  <!-- gallery item end -->\n\n                <\/div>\n                                <div class=\"swiper-slide\">\n\n                  <!-- gallery item -->\n                  <div class=\"knsl-image-frame\">\n                  \t                    \t\t\t\t\t<a data-elementor-lightbox-slideshow=\"about-gallery\" data-elementor-lightbox-title=\"\" href=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/htl-aurora-app-venus-4260-14.jpg\">\n\t\t\t\t\t                      <img decoding=\"async\" src=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/htl-aurora-app-venus-4260-14.jpg\" alt=\"\" \/>\n                                            <span class=\"knsl-zoom\"><i class=\"fas fa-search-plus\"><\/i><\/span>\n                    <\/a>\n                                      <\/div>\n                  <!-- gallery item end -->\n\n                <\/div>\n                                <div class=\"swiper-slide\">\n\n                  <!-- gallery item -->\n                  <div class=\"knsl-image-frame\">\n                  \t                    \t\t\t\t\t<a data-elementor-lightbox-slideshow=\"about-gallery\" data-elementor-lightbox-title=\"\" href=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/htl-aurora-app-venus-4262-15.jpg\">\n\t\t\t\t\t                      <img decoding=\"async\" src=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/htl-aurora-app-venus-4262-15.jpg\" alt=\"\" \/>\n                                            <span class=\"knsl-zoom\"><i class=\"fas fa-search-plus\"><\/i><\/span>\n                    <\/a>\n                                      <\/div>\n                  <!-- gallery item end -->\n\n                <\/div>\n                                <div class=\"swiper-slide\">\n\n                  <!-- gallery item -->\n                  <div class=\"knsl-image-frame\">\n                  \t                    \t\t\t\t\t<a data-elementor-lightbox-slideshow=\"about-gallery\" data-elementor-lightbox-title=\"\" href=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/htl-aurora-app-venus-4263-16.jpg\">\n\t\t\t\t\t                      <img decoding=\"async\" src=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/htl-aurora-app-venus-4263-16.jpg\" alt=\"\" \/>\n                                            <span class=\"knsl-zoom\"><i class=\"fas fa-search-plus\"><\/i><\/span>\n                    <\/a>\n                                      <\/div>\n                  <!-- gallery item end -->\n\n                <\/div>\n                                <div class=\"swiper-slide\">\n\n                  <!-- gallery item -->\n                  <div class=\"knsl-image-frame\">\n                  \t                    \t\t\t\t\t<a data-elementor-lightbox-slideshow=\"about-gallery\" data-elementor-lightbox-title=\"\" href=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/htl-aurora-app-venus-4268-18.jpg\">\n\t\t\t\t\t                      <img decoding=\"async\" src=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/htl-aurora-app-venus-4268-18.jpg\" alt=\"\" \/>\n                                            <span class=\"knsl-zoom\"><i class=\"fas fa-search-plus\"><\/i><\/span>\n                    <\/a>\n                                      <\/div>\n                  <!-- gallery item end -->\n\n                <\/div>\n                                <div class=\"swiper-slide\">\n\n                  <!-- gallery item -->\n                  <div class=\"knsl-image-frame\">\n                  \t                    \t\t\t\t\t<a data-elementor-lightbox-slideshow=\"about-gallery\" data-elementor-lightbox-title=\"\" href=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/htl-aurora-app-venus-4245-7.jpg\">\n\t\t\t\t\t                      <img decoding=\"async\" src=\"https:\/\/www.hotelauroraelba.it\/wp-content\/uploads\/2024\/11\/htl-aurora-app-venus-4245-7.jpg\" alt=\"\" \/>\n                                            <span class=\"knsl-zoom\"><i class=\"fas fa-search-plus\"><\/i><\/span>\n                    <\/a>\n                                      <\/div>\n                  <!-- gallery item end -->\n\n                <\/div>\n                              <\/div>\n\n              <!-- slider navigation -->\n              <div class=\"knsl-slider-nav-panel\">\n                <!-- pagination -->\n                <div class=\"knsl-about-slider-1-pagination\"><\/div>\n                <!-- navigation -->\n                <div class=\"knsl-about-slider-nav\">\n                  <div class=\"knsl-about-slider-1-prev\"><i class=\"fas fa-arrow-left\"><\/i><\/div>\n                  <div class=\"knsl-about-slider-1-next\"><i class=\"fas fa-arrow-right\"><\/i><\/div>\n                <\/div>\n                <!-- navigation end -->\n              <\/div>\n              <!-- slider navigation end -->\n\n            <\/div>\n            <!-- slider end -->\n\n          <\/div>\n          \n        <\/div>\n\t\t\n    <\/section>\n    <!-- gallery end -->\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Venus Apartment Home Apartments for 6 people Outdoor patio with a sea view Located on the ground floor, this apartment&#8230; <span class=\"knsl-el-more\"><a href=\"https:\/\/www.hotelauroraelba.it\/en\/apartments\/venus\/\" class=\"knsl-btn\">Read more<span class=\"screen-reader-text\">Read more&nbsp;Venus apartment<\/span><\/a><\/span><\/p>\n","protected":false},"author":2,"featured_media":0,"parent":9845,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-layout-builder.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-9851","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.hotelauroraelba.it\/en\/wp-json\/wp\/v2\/pages\/9851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hotelauroraelba.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hotelauroraelba.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hotelauroraelba.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hotelauroraelba.it\/en\/wp-json\/wp\/v2\/comments?post=9851"}],"version-history":[{"count":5,"href":"https:\/\/www.hotelauroraelba.it\/en\/wp-json\/wp\/v2\/pages\/9851\/revisions"}],"predecessor-version":[{"id":10347,"href":"https:\/\/www.hotelauroraelba.it\/en\/wp-json\/wp\/v2\/pages\/9851\/revisions\/10347"}],"up":[{"embeddable":true,"href":"https:\/\/www.hotelauroraelba.it\/en\/wp-json\/wp\/v2\/pages\/9845"}],"wp:attachment":[{"href":"https:\/\/www.hotelauroraelba.it\/en\/wp-json\/wp\/v2\/media?parent=9851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}